{"id":4033,"date":"2026-04-27T17:02:31","date_gmt":"2026-04-27T17:02:31","guid":{"rendered":"https:\/\/charming-buck.93-93-118-175.plesk.page\/?page_id=4033"},"modified":"2026-04-28T10:15:12","modified_gmt":"2026-04-28T10:15:12","slug":"ciclos-formativos-de-grado-superior","status":"publish","type":"page","link":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/ciclos-formativos-de-grado-superior\/","title":{"rendered":"Ciclos formativos de grado superior"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#0a0000&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_type=\u00bbcircular\u00bb background_color_gradient_stops=\u00bbrgba(51,51,51,0.5) 0%|rgba(1,10,6,0.5) 100%\u00bb background_color_gradient_overlays_image=\u00bbon\u00bb background_image=\u00bbhttps:\/\/charming-buck.93-93-118-175.plesk.page\/wp-content\/uploads\/2025\/05\/2148804524.jpg\u00bb background_position=\u00bbtop_left\u00bb background_vertical_offset=\u00bb45%\u00bb background_blend=\u00bbdarken\u00bb custom_padding=\u00bb||||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbCiclos Formativos de Grado Superior\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbFujiyama 2|300|||||||\u00bb title_text_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb2_5,3_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb text_text_color=\u00bb#6D004C\u00bb custom_margin=\u00bb35px||35px||true|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span>Los ciclos formativos de grado medio y grado superior est\u00e1n dise\u00f1ados para prepararte en una actividad profesional espec\u00edfica. Un\u00a0<strong>grado superior<\/strong>\u00a0te brindar\u00e1 una formaci\u00f3n que te capacitar\u00e1 para desarrollar actividades de forma aut\u00f3noma, con responsabilidad en la coordinaci\u00f3n y la supervisi\u00f3n de trabajos t\u00e9cnicos y especializados. Estos ciclos est\u00e1n asociados a est\u00e1ndares de competencia de<strong>\u00a0nivel 3 del Cat\u00e1logo Nacional de Est\u00e1ndares de Competencias Profesionales<\/strong><\/span><\/p>\n<p><span><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbdata:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTA4MCIgaGVpZ2h0PSI1NDAiIHZpZXdCb3g9IjAgMCAxMDgwIDU0MCIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIj4KICAgIDxnIGZpbGw9Im5vbmUiIGZpbGwtcnVsZT0iZXZlbm9kZCI+CiAgICAgICAgPHBhdGggZmlsbD0iI0VCRUJFQiIgZD0iTTAgMGgxMDgwdjU0MEgweiIvPgogICAgICAgIDxwYXRoIGQ9Ik00NDUuNjQ5IDU0MGgtOTguOTk1TDE0NC42NDkgMzM3Ljk5NSAwIDQ4Mi42NDR2LTk4Ljk5NWwxMTYuMzY1LTExNi4zNjVjMTUuNjItMTUuNjIgNDAuOTQ3LTE1LjYyIDU2LjU2OCAwTDQ0NS42NSA1NDB6IiBmaWxsLW9wYWNpdHk9Ii4xIiBmaWxsPSIjMDAwIiBmaWxsLXJ1bGU9Im5vbnplcm8iLz4KICAgICAgICA8Y2lyY2xlIGZpbGwtb3BhY2l0eT0iLjA1IiBmaWxsPSIjMDAwIiBjeD0iMzMxIiBjeT0iMTQ4IiByPSI3MCIvPgogICAgICAgIDxwYXRoIGQ9Ik0xMDgwIDM3OXYxMTMuMTM3TDcyOC4xNjIgMTQwLjMgMzI4LjQ2MiA1NDBIMjE1LjMyNEw2OTkuODc4IDU1LjQ0NmMxNS42Mi0xNS42MiA0MC45NDgtMTUuNjIgNTYuNTY4IDBMMTA4MCAzNzl6IiBmaWxsLW9wYWNpdHk9Ii4yIiBmaWxsPSIjMDAwIiBmaWxsLXJ1bGU9Im5vbnplcm8iLz4KICAgIDwvZz4KPC9zdmc+Cg==\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset1&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider color=\u00bb#F16CB9&#8243; divider_weight=\u00bb3px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb text_text_color=\u00bb#6D004C\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span>Tanto en los ciclos formativos de grado medio como en los de grado superior, las ense\u00f1anzas se organizan en dos cursos, durante los cuales desarrollar\u00e1s parte de tu formaci\u00f3n de manera pr\u00e1ctica en <strong>empresas u organismos equiparados<\/strong>. Adem\u00e1s, algunos grados medio y superior te permiten acceder a una formaci\u00f3n de grado E (cursos de especializaci\u00f3n).<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbdata:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTA4MCIgaGVpZ2h0PSI1NDAiIHZpZXdCb3g9IjAgMCAxMDgwIDU0MCIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIj4KICAgIDxnIGZpbGw9Im5vbmUiIGZpbGwtcnVsZT0iZXZlbm9kZCI+CiAgICAgICAgPHBhdGggZmlsbD0iI0VCRUJFQiIgZD0iTTAgMGgxMDgwdjU0MEgweiIvPgogICAgICAgIDxwYXRoIGQ9Ik00NDUuNjQ5IDU0MGgtOTguOTk1TDE0NC42NDkgMzM3Ljk5NSAwIDQ4Mi42NDR2LTk4Ljk5NWwxMTYuMzY1LTExNi4zNjVjMTUuNjItMTUuNjIgNDAuOTQ3LTE1LjYyIDU2LjU2OCAwTDQ0NS42NSA1NDB6IiBmaWxsLW9wYWNpdHk9Ii4xIiBmaWxsPSIjMDAwIiBmaWxsLXJ1bGU9Im5vbnplcm8iLz4KICAgICAgICA8Y2lyY2xlIGZpbGwtb3BhY2l0eT0iLjA1IiBmaWxsPSIjMDAwIiBjeD0iMzMxIiBjeT0iMTQ4IiByPSI3MCIvPgogICAgICAgIDxwYXRoIGQ9Ik0xMDgwIDM3OXYxMTMuMTM3TDcyOC4xNjIgMTQwLjMgMzI4LjQ2MiA1NDBIMjE1LjMyNEw2OTkuODc4IDU1LjQ0NmMxNS42Mi0xNS42MiA0MC45NDgtMTUuNjIgNTYuNTY4IDBMMTA4MCAzNzl6IiBmaWxsLW9wYWNpdHk9Ii4yIiBmaWxsPSIjMDAwIiBmaWxsLXJ1bGU9Im5vbnplcm8iLz4KICAgIDwvZz4KPC9zdmc+Cg==\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset1&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbdata:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTA4MCIgaGVpZ2h0PSI1NDAiIHZpZXdCb3g9IjAgMCAxMDgwIDU0MCIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIj4KICAgIDxnIGZpbGw9Im5vbmUiIGZpbGwtcnVsZT0iZXZlbm9kZCI+CiAgICAgICAgPHBhdGggZmlsbD0iI0VCRUJFQiIgZD0iTTAgMGgxMDgwdjU0MEgweiIvPgogICAgICAgIDxwYXRoIGQ9Ik00NDUuNjQ5IDU0MGgtOTguOTk1TDE0NC42NDkgMzM3Ljk5NSAwIDQ4Mi42NDR2LTk4Ljk5NWwxMTYuMzY1LTExNi4zNjVjMTUuNjItMTUuNjIgNDAuOTQ3LTE1LjYyIDU2LjU2OCAwTDQ0NS42NSA1NDB6IiBmaWxsLW9wYWNpdHk9Ii4xIiBmaWxsPSIjMDAwIiBmaWxsLXJ1bGU9Im5vbnplcm8iLz4KICAgICAgICA8Y2lyY2xlIGZpbGwtb3BhY2l0eT0iLjA1IiBmaWxsPSIjMDAwIiBjeD0iMzMxIiBjeT0iMTQ4IiByPSI3MCIvPgogICAgICAgIDxwYXRoIGQ9Ik0xMDgwIDM3OXYxMTMuMTM3TDcyOC4xNjIgMTQwLjMgMzI4LjQ2MiA1NDBIMjE1LjMyNEw2OTkuODc4IDU1LjQ0NmMxNS42Mi0xNS42MiA0MC45NDgtMTUuNjIgNTYuNTY4IDBMMTA4MCAzNzl6IiBmaWxsLW9wYWNpdHk9Ii4yIiBmaWxsPSIjMDAwIiBmaWxsLXJ1bGU9Im5vbnplcm8iLz4KICAgIDwvZz4KPC9zdmc+Cg==\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset1&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600|||||||\u00bb text_text_color=\u00bb#6D004C\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span>Al concluir el ciclo, obtendr\u00e1s la\u00a0<\/span><strong>titulaci\u00f3n de T\u00e9cnico\/a Superior<\/strong><span>\u00a0de la profesi\u00f3n correspondiente al grado cursado.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider color=\u00bb#F16CB9&#8243; divider_weight=\u00bb3px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbOferta en nuestro centro:\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh2&#8243; title_font=\u00bbFujiyama 2|300|||||||\u00bb title_text_align=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbAdministraci\u00f3n y finanzas\u00bb url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/portales\/web\/formacion-profesional-andaluza\/grado-superior-catalogo-de-titulos\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#F16CB9&#8243; global_colors_info=\u00bb{}\u00bb title_text_color__hover_enabled=\u00bbon|hover\u00bb title_text_color__hover=\u00bb#6D004C\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|hover\u00bb transform_rotate__hover_enabled=\u00bbon|hover\u00bb transform_skew__hover_enabled=\u00bbon|hover\u00bb transform_origin__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover=\u00bb110%|110%\u00bb][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bb\u00d3ptica de anteojer\u00eda\u00bb url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/portales\/web\/formacion-profesional-andaluza\/grado-superior-catalogo-de-titulos\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#F16CB9&#8243; custom_margin=\u00bb||||true|false\u00bb global_colors_info=\u00bb{}\u00bb title_text_color__hover_enabled=\u00bbon|hover\u00bb title_text_color__hover=\u00bb#6D004C\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|hover\u00bb transform_rotate__hover_enabled=\u00bbon|hover\u00bb transform_skew__hover_enabled=\u00bbon|hover\u00bb transform_origin__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover=\u00bb110%|110%\u00bb][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbSistemas de telecomunicaciones e inform\u00e1ticos\u00bb url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/portales\/web\/formacion-profesional-andaluza\/grado-superior-catalogo-de-titulos\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#F16CB9&#8243; global_colors_info=\u00bb{}\u00bb title_text_color__hover_enabled=\u00bbon|hover\u00bb title_text_color__hover=\u00bb#6D004C\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|hover\u00bb transform_rotate__hover_enabled=\u00bbon|hover\u00bb transform_skew__hover_enabled=\u00bbon|hover\u00bb transform_origin__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover=\u00bb110%|110%\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbProyectos de obra civil\u00bb url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/portales\/web\/formacion-profesional-andaluza\/grado-superior-catalogo-de-titulos\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#F16CB9&#8243; custom_margin=\u00bb||||true|false\u00bb global_colors_info=\u00bb{}\u00bb title_text_color__hover_enabled=\u00bbon|hover\u00bb title_text_color__hover=\u00bb#6D004C\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|hover\u00bb transform_rotate__hover_enabled=\u00bbon|hover\u00bb transform_skew__hover_enabled=\u00bbon|hover\u00bb transform_origin__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover=\u00bb110%|110%\u00bb][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbOrganizaci\u00f3n y control de obras\u00bb url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/portales\/web\/formacion-profesional-andaluza\/grado-superior-catalogo-de-titulos\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#F16CB9&#8243; global_colors_info=\u00bb{}\u00bb title_text_color__hover_enabled=\u00bbon|hover\u00bb title_text_color__hover=\u00bb#6D004C\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|hover\u00bb transform_rotate__hover_enabled=\u00bbon|hover\u00bb transform_skew__hover_enabled=\u00bbon|hover\u00bb transform_origin__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover=\u00bb110%|110%\u00bb][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbProyectos de edificaci\u00f3n\u00bb url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/portales\/web\/formacion-profesional-andaluza\/grado-superior-catalogo-de-titulos\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#F16CB9&#8243; global_colors_info=\u00bb{}\u00bb title_text_color__hover_enabled=\u00bbon|hover\u00bb title_text_color__hover=\u00bb#6D004C\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|hover\u00bb transform_rotate__hover_enabled=\u00bbon|hover\u00bb transform_skew__hover_enabled=\u00bbon|hover\u00bb transform_origin__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover=\u00bb110%|110%\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbAdministraci\u00f3n de sistemas inform\u00e1ticos en red (turno de tarde)\u00bb url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/portales\/web\/formacion-profesional-andaluza\/grado-superior-catalogo-de-titulos\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#F16CB9&#8243; custom_margin=\u00bb||||true|false\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb title_text_color__hover_enabled=\u00bbon|hover\u00bb title_text_color__hover=\u00bb#6D004C\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|hover\u00bb transform_rotate__hover_enabled=\u00bbon|hover\u00bb transform_skew__hover_enabled=\u00bbon|hover\u00bb transform_origin__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover=\u00bb110%|110%\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbDesarrollo de aplicaciones multiplataforma\u00bb url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/portales\/web\/formacion-profesional-andaluza\/grado-superior-catalogo-de-titulos\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#F16CB9&#8243; global_colors_info=\u00bb{}\u00bb title_text_color__hover_enabled=\u00bbon|hover\u00bb title_text_color__hover=\u00bb#6D004C\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|hover\u00bb transform_rotate__hover_enabled=\u00bbon|hover\u00bb transform_skew__hover_enabled=\u00bbon|hover\u00bb transform_origin__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover=\u00bb110%|110%\u00bb][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbDesarrollo de aplicaciones web\u00bb url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/portales\/web\/formacion-profesional-andaluza\/grado-superior-catalogo-de-titulos\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#F16CB9&#8243; global_colors_info=\u00bb{}\u00bb title_text_color__hover_enabled=\u00bbon|hover\u00bb title_text_color__hover=\u00bb#6D004C\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|hover\u00bb transform_rotate__hover_enabled=\u00bbon|hover\u00bb transform_skew__hover_enabled=\u00bbon|hover\u00bb transform_origin__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover=\u00bb110%|110%\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider color=\u00bb#F16CB9&#8243; divider_weight=\u00bb3px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjU2NjYifX0=@\u00bb button_text=\u00bbPasarela de Admisi\u00f3n y Matriculaci\u00f3n\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#F16CB9&#8243; button_bg_color=\u00bbRGBA(255,255,255,0)\u00bb button_border_color=\u00bbRGBA(255,255,255,0)\u00bb button_font=\u00bb|700|||||||\u00bb global_colors_info=\u00bb{}\u00bb button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#6D004C\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|desktop\u00bb transform_rotate__hover_enabled=\u00bbon|desktop\u00bb transform_skew__hover_enabled=\u00bbon|desktop\u00bb transform_origin__hover_enabled=\u00bbon|desktop\u00bb transform_scale__hover=\u00bb110%|110%\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider color=\u00bb#F16CB9&#8243; divider_weight=\u00bb3px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbM\u00e1s Informaci\u00f3n\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh2&#8243; title_font=\u00bbFujiyama 2||||||||\u00bb title_text_align=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_button button_url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/portales\/web\/escolarizacion\/formacion-profesional\/d-grado-medio-grado-superior\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbVer m\u00e1s\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los ciclos formativos de grado medio y grado superior est\u00e1n dise\u00f1ados para prepararte en una actividad profesional espec\u00edfica. Un\u00a0grado superior\u00a0te brindar\u00e1 una formaci\u00f3n que te capacitar\u00e1 para desarrollar actividades de forma aut\u00f3noma, con responsabilidad en la coordinaci\u00f3n y la supervisi\u00f3n de trabajos t\u00e9cnicos y especializados. Estos ciclos est\u00e1n asociados a est\u00e1ndares de competencia de\u00a0nivel 3 [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-4033","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ciclos formativos de grado superior - IES Fernando Aguilar Quignon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/ciclos-formativos-de-grado-superior\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ciclos formativos de grado superior - IES Fernando Aguilar Quignon\" \/>\n<meta property=\"og:description\" content=\"Los ciclos formativos de grado medio y grado superior est\u00e1n dise\u00f1ados para prepararte en una actividad profesional espec\u00edfica. Un\u00a0grado superior\u00a0te brindar\u00e1 una formaci\u00f3n que te capacitar\u00e1 para desarrollar actividades de forma aut\u00f3noma, con responsabilidad en la coordinaci\u00f3n y la supervisi\u00f3n de trabajos t\u00e9cnicos y especializados. Estos ciclos est\u00e1n asociados a est\u00e1ndares de competencia de\u00a0nivel 3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/ciclos-formativos-de-grado-superior\/\" \/>\n<meta property=\"og:site_name\" content=\"IES Fernando Aguilar Quignon\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T10:15:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/ciclos-formativos-de-grado-superior\\\/\",\"url\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/ciclos-formativos-de-grado-superior\\\/\",\"name\":\"Ciclos formativos de grado superior - IES Fernando Aguilar Quignon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/#website\"},\"datePublished\":\"2026-04-27T17:02:31+00:00\",\"dateModified\":\"2026-04-28T10:15:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/ciclos-formativos-de-grado-superior\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/ciclos-formativos-de-grado-superior\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/ciclos-formativos-de-grado-superior\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ciclos formativos de grado superior\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/#website\",\"url\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/\",\"name\":\"IES Fernando Aguilar Quignon\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ciclos formativos de grado superior - IES Fernando Aguilar Quignon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/ciclos-formativos-de-grado-superior\/","og_locale":"es_ES","og_type":"article","og_title":"Ciclos formativos de grado superior - IES Fernando Aguilar Quignon","og_description":"Los ciclos formativos de grado medio y grado superior est\u00e1n dise\u00f1ados para prepararte en una actividad profesional espec\u00edfica. Un\u00a0grado superior\u00a0te brindar\u00e1 una formaci\u00f3n que te capacitar\u00e1 para desarrollar actividades de forma aut\u00f3noma, con responsabilidad en la coordinaci\u00f3n y la supervisi\u00f3n de trabajos t\u00e9cnicos y especializados. Estos ciclos est\u00e1n asociados a est\u00e1ndares de competencia de\u00a0nivel 3 [&hellip;]","og_url":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/ciclos-formativos-de-grado-superior\/","og_site_name":"IES Fernando Aguilar Quignon","article_modified_time":"2026-04-28T10:15:12+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/ciclos-formativos-de-grado-superior\/","url":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/ciclos-formativos-de-grado-superior\/","name":"Ciclos formativos de grado superior - IES Fernando Aguilar Quignon","isPartOf":{"@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/#website"},"datePublished":"2026-04-27T17:02:31+00:00","dateModified":"2026-04-28T10:15:12+00:00","breadcrumb":{"@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/ciclos-formativos-de-grado-superior\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/ciclos-formativos-de-grado-superior\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/ciclos-formativos-de-grado-superior\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/charming-buck.93-93-118-175.plesk.page\/"},{"@type":"ListItem","position":2,"name":"Ciclos formativos de grado superior"}]},{"@type":"WebSite","@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/#website","url":"https:\/\/charming-buck.93-93-118-175.plesk.page\/","name":"IES Fernando Aguilar Quignon","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/charming-buck.93-93-118-175.plesk.page\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/pages\/4033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/comments?post=4033"}],"version-history":[{"count":10,"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/pages\/4033\/revisions"}],"predecessor-version":[{"id":6224,"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/pages\/4033\/revisions\/6224"}],"wp:attachment":[{"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/media?parent=4033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}