{"id":6113,"date":"2025-05-27T21:19:19","date_gmt":"2025-05-27T21:19:19","guid":{"rendered":"https:\/\/charming-buck.93-93-118-175.plesk.page\/?page_id=6113"},"modified":"2026-05-27T15:50:07","modified_gmt":"2026-05-27T15:50:07","slug":"grado-basico-pam","status":"publish","type":"page","link":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/grado-basico-pam\/","title":{"rendered":"Grado B\u00e1sico PAM"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#0a0000&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_type=\u00bbcircular\u00bb background_color_gradient_stops=\u00bbrgba(51,51,51,0.5) 0%|rgba(1,10,6,0.5) 100%\u00bb background_color_gradient_overlays_image=\u00bbon\u00bb background_image=\u00bbhttps:\/\/charming-buck.93-93-118-175.plesk.page\/wp-content\/uploads\/2025\/05\/2150263116.jpg\u00bb background_position=\u00bbtop_left\u00bb background_vertical_offset=\u00bb71%\u00bb background_blend=\u00bbdarken\u00bb custom_padding=\u00bb||||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbGrado B\u00e1sico | Pasarela de Admisi\u00f3n y Matriculaci\u00f3n\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbFujiyama 2|300|||||||\u00bb title_text_color=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbGRADO B\u00c1SICO (Alumnado del centro que repite o promociona de curso)\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh2&#8243; title_font=\u00bbFujiyama 2|300|||||||\u00bb border_width_bottom=\u00bb2px\u00bb border_color_bottom=\u00bb#F16CB9&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbAdmisi\u00f3n\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#F16CB9&#8243; border_width_bottom=\u00bb1px\u00bb border_color_bottom=\u00bb#F16CB9&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_heading title=\u00bbEl alumnado del centro que ya est\u00e1 matriculado en Grado B\u00e1sico y que promociona o repite curso, no necesita Solicitud de Admisi\u00f3n. Se matricula directamente en el curo que corresponda\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh5&#8243; title_font=\u00bb||||||||\u00bb title_text_align=\u00bbcenter\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_heading][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p style=\"text-align: center;\">\u2192<\/p>\n<p>[\/et_pb_text][et_pb_button url_new_window=\u00bbon\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_bg_color=\u00bb#CCCCCC\u00bb button_font=\u00bb||||||||\u00bb button_icon=\u00bb&#x24;||divi||400&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_divider color=\u00bb#6D004C\u00bb divider_weight=\u00bb3px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbMatriculaci\u00f3n\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#F16CB9&#8243; border_width_bottom=\u00bb1px\u00bb border_color_bottom=\u00bb#F16CB9&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_heading title=\u00bbMatr\u00edcula del 25 al 30 de Junio\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh4&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_button button_url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/secretariavirtual\/accesoConsultas\/1712\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbEn espera\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_bg_color=\u00bb#CCCCCC\u00bb button_font=\u00bb||||||||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_divider color=\u00bb#6D004C\u00bb divider_weight=\u00bb3px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbGRADO B\u00c1SICO (Alumnado de nuevo ingreso en 1\u00ba)\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh2&#8243; title_font=\u00bbFujiyama 2|300|||||||\u00bb border_width_bottom=\u00bb2px\u00bb border_color_bottom=\u00bb#F16CB9&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbAdmisi\u00f3n\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#F16CB9&#8243; border_width_bottom=\u00bb1px\u00bb border_color_bottom=\u00bb#F16CB9&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_heading title=\u00bbSolicitud de Admisi\u00f3n: Del 15 al 30 de Junio\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh4&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_button button_url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/secretariavirtual\/accesoTramite\/265\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbEn espera\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#CCCCCC\u00bb button_font=\u00bb||||||||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_divider color=\u00bb#6D004C\u00bb divider_weight=\u00bb3px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_heading title=\u00bbConsulta Provisional de Solicitantes: 2 de Julio\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh4&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_button button_url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/secretariavirtual\/accesoConsultas\/1710\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbEn espera\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_bg_color=\u00bb#CCCCCC\u00bb button_font=\u00bb||||||||\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_divider color=\u00bb#6D004C\u00bb divider_weight=\u00bb3px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_heading title=\u00bbReclamaciones Lista Solicitantes: Del 3 al 6 de Julio\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh4&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_button button_url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/secretariavirtual\/accesoTramite\/285\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbEn espera\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_bg_color=\u00bb#CCCCCC\u00bb button_font=\u00bb||||||||\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_divider color=\u00bb#6D004C\u00bb divider_weight=\u00bb3px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_heading title=\u00bbConsulta Definitiva de Solilcitantes: 9 de Julio\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh4&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_button button_url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/secretariavirtual\/accesoConsultas\/1711\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbEn espera\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_bg_color=\u00bb#CCCCCC\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbMatriculaci\u00f3n\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#F16CB9&#8243; border_width_bottom=\u00bb1px\u00bb border_color_bottom=\u00bb#F16CB9&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_heading title=\u00bbConsulta 1\u00aa Adjudicaci\u00f3n: 9 de Julio\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh4&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_button button_url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/secretariavirtual\/accesoConsultas\/1712\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbEn espera\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_bg_color=\u00bb#CCCCCC\u00bb button_font=\u00bb||||||||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_divider color=\u00bb#6D004C\u00bb divider_weight=\u00bb3px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_heading title=\u00bbReserva 1\u00aa Adjudicaci\u00f3n: Del 10 al 15 de Julio\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh4&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb hover_enabled=\u00bb0&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_heading][et_pb_button button_url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/secretariavirtual\/accesoTramite\/265\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbEn espera\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_font=\u00bb||||||||\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb button_bg_color=\u00bb#CCCCCC\u00bb button_bg_enable_color=\u00bbon\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_button][et_pb_divider color=\u00bb#6D004C\u00bb divider_style=\u00bbdotted\u00bb divider_weight=\u00bb3px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_heading title=\u00bbMatr\u00edcula 1\u00aa Adjudicaci\u00f3n: Del 10 al 15 de Julio\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh4&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb hover_enabled=\u00bb0&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_heading][et_pb_button button_url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/secretariavirtual\/accesoTramite\/265\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbEn espera\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_font=\u00bb||||||||\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb button_bg_color=\u00bb#CCCCCC\u00bb button_bg_enable_color=\u00bbon\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_button][et_pb_divider color=\u00bb#6D004C\u00bb divider_weight=\u00bb3px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_heading title=\u00bbConsulta 2\u00aa Adjudicaci\u00f3n: 20 Julio\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh4&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb hover_enabled=\u00bb0&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_heading][et_pb_button button_url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/secretariavirtual\/accesoTramite\/265\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbEn espera\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_font=\u00bb||||||||\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb button_bg_color=\u00bb#CCCCCC\u00bb button_bg_enable_color=\u00bbon\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_button][et_pb_divider color=\u00bb#6D004C\u00bb divider_weight=\u00bb3px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_heading title=\u00bbMatr\u00edcula 2\u00aa Adjudicaci\u00f3n: Del 21 al 23 Julio\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh4&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb hover_enabled=\u00bb0&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_heading][et_pb_heading title=\u00bbMatr\u00edcula 2\u00aa Adjudicaci\u00f3n\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh4&#8243; title_font=\u00bb|600|||||||\u00bb title_text_align=\u00bbcenter\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_button button_url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/secretariavirtual\/accesoTramite\/265\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbEn espera\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_font=\u00bb||||||||\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb button_bg_color=\u00bb#CCCCCC\u00bb button_bg_enable_color=\u00bbon\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider color=\u00bb#6D004C\u00bb divider_weight=\u00bb3px\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjU2NjYifX0=@\u00bb button_text=\u00bbVolver\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bbbutton_url\u00bb _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2192<\/p>\n","protected":false},"author":11,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","footnotes":""},"class_list":["post-6113","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grado B\u00e1sico PAM - IES Fernando Aguilar Quignon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/grado-basico-pam\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grado B\u00e1sico PAM - IES Fernando Aguilar Quignon\" \/>\n<meta property=\"og:description\" content=\"\u2192\" \/>\n<meta property=\"og:url\" content=\"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/grado-basico-pam\/\" \/>\n<meta property=\"og:site_name\" content=\"IES Fernando Aguilar Quignon\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-27T15:50:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/grado-basico-pam\\\/\",\"url\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/grado-basico-pam\\\/\",\"name\":\"Grado B\u00e1sico PAM - IES Fernando Aguilar Quignon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/#website\"},\"datePublished\":\"2025-05-27T21:19:19+00:00\",\"dateModified\":\"2026-05-27T15:50:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/grado-basico-pam\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/grado-basico-pam\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/grado-basico-pam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grado B\u00e1sico PAM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/#website\",\"url\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/\",\"name\":\"IES Fernando Aguilar Quignon\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grado B\u00e1sico PAM - IES Fernando Aguilar Quignon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/grado-basico-pam\/","og_locale":"es_ES","og_type":"article","og_title":"Grado B\u00e1sico PAM - IES Fernando Aguilar Quignon","og_description":"\u2192","og_url":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/grado-basico-pam\/","og_site_name":"IES Fernando Aguilar Quignon","article_modified_time":"2026-05-27T15:50:07+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/grado-basico-pam\/","url":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/grado-basico-pam\/","name":"Grado B\u00e1sico PAM - IES Fernando Aguilar Quignon","isPartOf":{"@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/#website"},"datePublished":"2025-05-27T21:19:19+00:00","dateModified":"2026-05-27T15:50:07+00:00","breadcrumb":{"@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/grado-basico-pam\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/grado-basico-pam\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/grado-basico-pam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/charming-buck.93-93-118-175.plesk.page\/"},{"@type":"ListItem","position":2,"name":"Grado B\u00e1sico PAM"}]},{"@type":"WebSite","@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/#website","url":"https:\/\/charming-buck.93-93-118-175.plesk.page\/","name":"IES Fernando Aguilar Quignon","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/charming-buck.93-93-118-175.plesk.page\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/pages\/6113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/comments?post=6113"}],"version-history":[{"count":8,"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/pages\/6113\/revisions"}],"predecessor-version":[{"id":6611,"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/pages\/6113\/revisions\/6611"}],"wp:attachment":[{"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/media?parent=6113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}