{"id":4619,"date":"2017-12-15T10:06:00","date_gmt":"2017-12-15T10:06:00","guid":{"rendered":"https:\/\/charming-buck.93-93-118-175.plesk.page\/?p=4619"},"modified":"2025-05-06T17:45:11","modified_gmt":"2025-05-06T17:45:11","slug":"campana-de-recogida-de-alimentos-2","status":"publish","type":"post","link":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/2017\/12\/15\/campana-de-recogida-de-alimentos-2\/","title":{"rendered":"CAMPA\u00d1A DE RECOGIDA DE ALIMENTOS"},"content":{"rendered":"\n[et_pb_section fb_built=\u00bb1&#8243; theme_builder_area=\u00bbpost_content\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p>Como cada a\u00f1o, hemos iniciado nuestra campa\u00f1a de Navidad: \u201cNavidad Solidaria\u201d, con el fin concienciar a nuestro alumnado y educar en la generosidad con los m\u00e1s desfavorecidos. Hemos colocado a la entrada del IES un espacio de recogida de alimentos no perecederos que entregaremos pr\u00f3ximamente a la Fundaci\u00f3n Virgen de Valvanuz que en su comedor social hace tanto bien para quienes necesitan solidaridad. Hasta el 21 de Diciembre puedes hacer tu aportaci\u00f3n. \u00a1Gracias!<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Como cada a\u00f1o, hemos iniciado nuestra campa\u00f1a de Navidad: \u201cNavidad Solidaria\u201d, con el fin concienciar a nuestro alumnado y educar en la generosidad con los m\u00e1s desfavorecidos. Hemos colocado a la entrada del IES un espacio de recogida de alimentos no perecederos que entregaremos pr\u00f3ximamente a la Fundaci\u00f3n Virgen de Valvanuz que en su comedor [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4223,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-4619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CAMPA\u00d1A DE RECOGIDA DE ALIMENTOS - IES Fernando Aguilar Quignon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/2017\/12\/15\/campana-de-recogida-de-alimentos-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAMPA\u00d1A DE RECOGIDA DE ALIMENTOS - IES Fernando Aguilar Quignon\" \/>\n<meta property=\"og:description\" content=\"Como cada a\u00f1o, hemos iniciado nuestra campa\u00f1a de Navidad: \u201cNavidad Solidaria\u201d, con el fin concienciar a nuestro alumnado y educar en la generosidad con los m\u00e1s desfavorecidos. Hemos colocado a la entrada del IES un espacio de recogida de alimentos no perecederos que entregaremos pr\u00f3ximamente a la Fundaci\u00f3n Virgen de Valvanuz que en su comedor [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/2017\/12\/15\/campana-de-recogida-de-alimentos-2\/\" \/>\n<meta property=\"og:site_name\" content=\"IES Fernando Aguilar Quignon\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-15T10:06:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-06T17:45:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/charming-buck.93-93-118-175.plesk.page\/wp-content\/uploads\/2025\/04\/campana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"435\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/2017\\\/12\\\/15\\\/campana-de-recogida-de-alimentos-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/2017\\\/12\\\/15\\\/campana-de-recogida-de-alimentos-2\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/#\\\/schema\\\/person\\\/130ae04b8db2760ec74a45c3461a007d\"},\"headline\":\"CAMPA\u00d1A DE RECOGIDA DE ALIMENTOS\",\"datePublished\":\"2017-12-15T10:06:00+00:00\",\"dateModified\":\"2025-05-06T17:45:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/2017\\\/12\\\/15\\\/campana-de-recogida-de-alimentos-2\\\/\"},\"wordCount\":155,\"image\":{\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/2017\\\/12\\\/15\\\/campana-de-recogida-de-alimentos-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/campana.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/2017\\\/12\\\/15\\\/campana-de-recogida-de-alimentos-2\\\/\",\"url\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/2017\\\/12\\\/15\\\/campana-de-recogida-de-alimentos-2\\\/\",\"name\":\"CAMPA\u00d1A DE RECOGIDA DE ALIMENTOS - IES Fernando Aguilar Quignon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/2017\\\/12\\\/15\\\/campana-de-recogida-de-alimentos-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/2017\\\/12\\\/15\\\/campana-de-recogida-de-alimentos-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/campana.jpg\",\"datePublished\":\"2017-12-15T10:06:00+00:00\",\"dateModified\":\"2025-05-06T17:45:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/#\\\/schema\\\/person\\\/130ae04b8db2760ec74a45c3461a007d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/2017\\\/12\\\/15\\\/campana-de-recogida-de-alimentos-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/2017\\\/12\\\/15\\\/campana-de-recogida-de-alimentos-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/2017\\\/12\\\/15\\\/campana-de-recogida-de-alimentos-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/campana.jpg\",\"contentUrl\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/campana.jpg\",\"width\":800,\"height\":435},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/2017\\\/12\\\/15\\\/campana-de-recogida-de-alimentos-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CAMPA\u00d1A DE RECOGIDA DE ALIMENTOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/#website\",\"url\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/\",\"name\":\"IES Fernando Aguilar Quignon\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/#\\\/schema\\\/person\\\/130ae04b8db2760ec74a45c3461a007d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\"],\"url\":\"https:\\\/\\\/charming-buck.93-93-118-175.plesk.page\\\/index.php\\\/author\\\/nimda_faq\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAMPA\u00d1A DE RECOGIDA DE ALIMENTOS - IES Fernando Aguilar Quignon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/2017\/12\/15\/campana-de-recogida-de-alimentos-2\/","og_locale":"es_ES","og_type":"article","og_title":"CAMPA\u00d1A DE RECOGIDA DE ALIMENTOS - IES Fernando Aguilar Quignon","og_description":"Como cada a\u00f1o, hemos iniciado nuestra campa\u00f1a de Navidad: \u201cNavidad Solidaria\u201d, con el fin concienciar a nuestro alumnado y educar en la generosidad con los m\u00e1s desfavorecidos. Hemos colocado a la entrada del IES un espacio de recogida de alimentos no perecederos que entregaremos pr\u00f3ximamente a la Fundaci\u00f3n Virgen de Valvanuz que en su comedor [&hellip;]","og_url":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/2017\/12\/15\/campana-de-recogida-de-alimentos-2\/","og_site_name":"IES Fernando Aguilar Quignon","article_published_time":"2017-12-15T10:06:00+00:00","article_modified_time":"2025-05-06T17:45:11+00:00","og_image":[{"width":800,"height":435,"url":"https:\/\/charming-buck.93-93-118-175.plesk.page\/wp-content\/uploads\/2025\/04\/campana.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/2017\/12\/15\/campana-de-recogida-de-alimentos-2\/#article","isPartOf":{"@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/2017\/12\/15\/campana-de-recogida-de-alimentos-2\/"},"author":{"name":"admin","@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/#\/schema\/person\/130ae04b8db2760ec74a45c3461a007d"},"headline":"CAMPA\u00d1A DE RECOGIDA DE ALIMENTOS","datePublished":"2017-12-15T10:06:00+00:00","dateModified":"2025-05-06T17:45:11+00:00","mainEntityOfPage":{"@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/2017\/12\/15\/campana-de-recogida-de-alimentos-2\/"},"wordCount":155,"image":{"@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/2017\/12\/15\/campana-de-recogida-de-alimentos-2\/#primaryimage"},"thumbnailUrl":"https:\/\/charming-buck.93-93-118-175.plesk.page\/wp-content\/uploads\/2025\/04\/campana.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/2017\/12\/15\/campana-de-recogida-de-alimentos-2\/","url":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/2017\/12\/15\/campana-de-recogida-de-alimentos-2\/","name":"CAMPA\u00d1A DE RECOGIDA DE ALIMENTOS - IES Fernando Aguilar Quignon","isPartOf":{"@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/#website"},"primaryImageOfPage":{"@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/2017\/12\/15\/campana-de-recogida-de-alimentos-2\/#primaryimage"},"image":{"@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/2017\/12\/15\/campana-de-recogida-de-alimentos-2\/#primaryimage"},"thumbnailUrl":"https:\/\/charming-buck.93-93-118-175.plesk.page\/wp-content\/uploads\/2025\/04\/campana.jpg","datePublished":"2017-12-15T10:06:00+00:00","dateModified":"2025-05-06T17:45:11+00:00","author":{"@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/#\/schema\/person\/130ae04b8db2760ec74a45c3461a007d"},"breadcrumb":{"@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/2017\/12\/15\/campana-de-recogida-de-alimentos-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/2017\/12\/15\/campana-de-recogida-de-alimentos-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/2017\/12\/15\/campana-de-recogida-de-alimentos-2\/#primaryimage","url":"https:\/\/charming-buck.93-93-118-175.plesk.page\/wp-content\/uploads\/2025\/04\/campana.jpg","contentUrl":"https:\/\/charming-buck.93-93-118-175.plesk.page\/wp-content\/uploads\/2025\/04\/campana.jpg","width":800,"height":435},{"@type":"BreadcrumbList","@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/2017\/12\/15\/campana-de-recogida-de-alimentos-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/charming-buck.93-93-118-175.plesk.page\/"},{"@type":"ListItem","position":2,"name":"CAMPA\u00d1A DE RECOGIDA DE ALIMENTOS"}]},{"@type":"WebSite","@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/#website","url":"https:\/\/charming-buck.93-93-118-175.plesk.page\/","name":"IES Fernando Aguilar Quignon","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/charming-buck.93-93-118-175.plesk.page\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/charming-buck.93-93-118-175.plesk.page\/#\/schema\/person\/130ae04b8db2760ec74a45c3461a007d","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a1c16aef58f42746e23046e8a7ec514e0aa90548a4fa54462df39dbe3d71242?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/charming-buck.93-93-118-175.plesk.page"],"url":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/author\/nimda_faq\/"}]}},"_links":{"self":[{"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/posts\/4619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/comments?post=4619"}],"version-history":[{"count":3,"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/posts\/4619\/revisions"}],"predecessor-version":[{"id":4622,"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/posts\/4619\/revisions\/4622"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/media\/4223"}],"wp:attachment":[{"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/media?parent=4619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/categories?post=4619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/charming-buck.93-93-118-175.plesk.page\/index.php\/wp-json\/wp\/v2\/tags?post=4619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}